{"id":214,"date":"2011-05-09T23:05:16","date_gmt":"2011-05-10T06:05:16","guid":{"rendered":"http:\/\/www.sounddoctrineministries.com\/Blog\/?p=214"},"modified":"2011-05-09T23:05:16","modified_gmt":"2011-05-10T06:05:16","slug":"victimas-de-la-ansiedad-2","status":"publish","type":"post","link":"https:\/\/www.sounddoctrineministries.com\/Blog\/victimas-de-la-ansiedad-2\/","title":{"rendered":"Victimas de la ansiedad"},"content":{"rendered":"<p>\u00bfVives constatemente preocupado? \u00bfPadeces enfermedades pero el doctor te  dice que todo est\u00e1 bien? Probablemente eres victima de la ansiedad, uno  de los problemas m\u00e1s serios y m\u00e1s comunes del mundo moderno? Aqu\u00ed est\u00e1  la soluci\u00f3n!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfVives constatemente preocupado? \u00bfPadeces enfermedades pero el doctor te dice que todo est\u00e1 bien? Probablemente eres victima de la ansiedad, uno de los problemas m\u00e1s serios y m\u00e1s comunes del mundo moderno? Aqu\u00ed est\u00e1 la soluci\u00f3n!<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-214","post","type-post","status-publish","format-standard","hentry","category-predicaciones"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.sounddoctrineministries.com\/Blog\/wp-json\/wp\/v2\/posts\/214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sounddoctrineministries.com\/Blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sounddoctrineministries.com\/Blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sounddoctrineministries.com\/Blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sounddoctrineministries.com\/Blog\/wp-json\/wp\/v2\/comments?post=214"}],"version-history":[{"count":1,"href":"https:\/\/www.sounddoctrineministries.com\/Blog\/wp-json\/wp\/v2\/posts\/214\/revisions"}],"predecessor-version":[{"id":215,"href":"https:\/\/www.sounddoctrineministries.com\/Blog\/wp-json\/wp\/v2\/posts\/214\/revisions\/215"}],"wp:attachment":[{"href":"https:\/\/www.sounddoctrineministries.com\/Blog\/wp-json\/wp\/v2\/media?parent=214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sounddoctrineministries.com\/Blog\/wp-json\/wp\/v2\/categories?post=214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sounddoctrineministries.com\/Blog\/wp-json\/wp\/v2\/tags?post=214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}