{"id":34,"date":"2010-03-15T19:17:13","date_gmt":"2010-03-16T02:17:13","guid":{"rendered":"http:\/\/www.sounddoctrineministries.com\/Blog\/?p=34"},"modified":"2011-04-15T16:02:56","modified_gmt":"2011-04-15T23:02:56","slug":"desertores-en-tiempo-de-guerra","status":"publish","type":"post","link":"https:\/\/www.sounddoctrineministries.com\/Blog\/desertores-en-tiempo-de-guerra\/","title":{"rendered":"Desertores en tiempo de guerra"},"content":{"rendered":"<p>[podcast]http:\/\/www.sounddoctrineministries.com\/Sermones\/Desertores en tiempo de guerra.mp3[\/podcast]<\/p>\n<p>No nos convirtamos en desertores especialmente cuando la batalla est\u00e1 en lo m\u00e1s recio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[podcast]http:\/\/www.sounddoctrineministries.com\/Sermones\/Desertores en tiempo de guerra.mp3[\/podcast] No nos convirtamos en desertores especialmente cuando la batalla est\u00e1 en lo m\u00e1s recio.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-34","post","type-post","status-publish","format-standard","hentry","category-predicaciones"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.sounddoctrineministries.com\/Blog\/wp-json\/wp\/v2\/posts\/34","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sounddoctrineministries.com\/Blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sounddoctrineministries.com\/Blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sounddoctrineministries.com\/Blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sounddoctrineministries.com\/Blog\/wp-json\/wp\/v2\/comments?post=34"}],"version-history":[{"count":4,"href":"https:\/\/www.sounddoctrineministries.com\/Blog\/wp-json\/wp\/v2\/posts\/34\/revisions"}],"predecessor-version":[{"id":193,"href":"https:\/\/www.sounddoctrineministries.com\/Blog\/wp-json\/wp\/v2\/posts\/34\/revisions\/193"}],"wp:attachment":[{"href":"https:\/\/www.sounddoctrineministries.com\/Blog\/wp-json\/wp\/v2\/media?parent=34"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sounddoctrineministries.com\/Blog\/wp-json\/wp\/v2\/categories?post=34"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sounddoctrineministries.com\/Blog\/wp-json\/wp\/v2\/tags?post=34"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}