{"id":90,"date":"2010-03-27T20:38:49","date_gmt":"2010-03-28T03:38:49","guid":{"rendered":"http:\/\/www.sounddoctrineministries.com\/Blog\/?p=90"},"modified":"2011-04-15T16:48:41","modified_gmt":"2011-04-15T23:48:41","slug":"fariseismo-fundamentalista-2","status":"publish","type":"post","link":"https:\/\/www.sounddoctrineministries.com\/Blog\/fariseismo-fundamentalista-2\/","title":{"rendered":"Farise\u00edsmo &#8220;fundamentalista&#8221;"},"content":{"rendered":"<p><a title=\"Solo ellos\" href=\"http:\/\/www.youtube.com\/watch?v=gCD4dJMNwCc&amp;feature=PlayList&amp;p=56CE5B73F416A7D0&amp;playnext=1&amp;playnext_from=PL&amp;index=8\">Solo los seminarios bautistas fundamentales independientes son buenos.<\/a><br \/>\nEn estos tiempos, el t\u00e9rmino &#8220;fundamentalista&#8221; ha sido minado por  aquellos que, en su ignorancia, claman que solo su creencia es la  correcta, y que otros creyentes que no siguen su l\u00ednea son liberales y  est\u00e1n mal.\u00a0 La llamada &#8220;separaci\u00f3n&#8221; es simplemente una aberraci\u00f3n de la  ense\u00f1anza b\u00edblica de separaci\u00f3n del pecado.\u00a0 Presione el link de arriba  para escucharlo de sus labios.\u00a0 \u00bfCu\u00e1l es tu opini\u00f3n?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Solo los seminarios bautistas fundamentales independientes son buenos. En estos tiempos, el t\u00e9rmino &#8220;fundamentalista&#8221; ha sido minado por aquellos que, en su ignorancia, claman que solo su creencia es la correcta, y que otros creyentes que no siguen su l\u00ednea son liberales y est\u00e1n mal.\u00a0 La llamada &#8220;separaci\u00f3n&#8221; es simplemente una aberraci\u00f3n de la ense\u00f1anza [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-90","post","type-post","status-publish","format-standard","hentry","category-discusiones-y-comentarios"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.sounddoctrineministries.com\/Blog\/wp-json\/wp\/v2\/posts\/90","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sounddoctrineministries.com\/Blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sounddoctrineministries.com\/Blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sounddoctrineministries.com\/Blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sounddoctrineministries.com\/Blog\/wp-json\/wp\/v2\/comments?post=90"}],"version-history":[{"count":7,"href":"https:\/\/www.sounddoctrineministries.com\/Blog\/wp-json\/wp\/v2\/posts\/90\/revisions"}],"predecessor-version":[{"id":206,"href":"https:\/\/www.sounddoctrineministries.com\/Blog\/wp-json\/wp\/v2\/posts\/90\/revisions\/206"}],"wp:attachment":[{"href":"https:\/\/www.sounddoctrineministries.com\/Blog\/wp-json\/wp\/v2\/media?parent=90"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sounddoctrineministries.com\/Blog\/wp-json\/wp\/v2\/categories?post=90"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sounddoctrineministries.com\/Blog\/wp-json\/wp\/v2\/tags?post=90"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}